{"id":1623,"date":"2015-10-29T16:15:34","date_gmt":"2015-10-29T15:15:34","guid":{"rendered":"http:\/\/www.lifeherotile.eu\/de\/life-herotile-sistemi-di-coperture-del-futuro\/"},"modified":"2016-05-02T13:02:33","modified_gmt":"2016-05-02T11:02:33","slug":"life-herotile-sistemi-di-coperture-del-futuro","status":"publish","type":"post","link":"https:\/\/www.lifeherotile.eu\/de\/life-herotile-sistemi-di-coperture-del-futuro\/","title":{"rendered":"Life Herotile: sistemi di coperture del futuro"},"content":{"rendered":"<p>http:\/\/www.edilizianews.it\/articolo\/21640\/life-herotile-sistemi-di-coperture-del-futuro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.edilizianews.it\/articolo\/21640\/life-herotile-sistemi-di-coperture-del-futuro<\/p>\n","protected":false},"author":2,"featured_media":1624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1623","post","type-post","status-publish","format-link","has-post-thumbnail","hentry","category-press-release-de","post_format-post-format-link"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Life Herotile: sistemi di coperture del futuro - lifeherotile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Life Herotile: sistemi di coperture del futuro - lifeherotile\" \/>\n<meta property=\"og:description\" content=\"http:\/\/www.edilizianews.it\/articolo\/21640\/life-herotile-sistemi-di-coperture-del-futuro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"lifeherotile\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-29T15:15:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-02T11:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"247\" \/>\n\t<meta property=\"og:image:height\" content=\"118\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia Zambelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Zambelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/\"},\"author\":{\"name\":\"Silvia Zambelli\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\"},\"headline\":\"Life Herotile: sistemi di coperture del futuro\",\"datePublished\":\"2015-10-29T15:15:34+00:00\",\"dateModified\":\"2016-05-02T11:02:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo-edilizia.jpg\",\"articleSection\":[\"Press Release\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/\",\"name\":\"Life Herotile: sistemi di coperture del futuro - lifeherotile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo-edilizia.jpg\",\"datePublished\":\"2015-10-29T15:15:34+00:00\",\"dateModified\":\"2016-05-02T11:02:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo-edilizia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/logo-edilizia.jpg\",\"width\":247,\"height\":118},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/life-herotile-sistemi-di-coperture-del-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lifeherotile.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life Herotile: sistemi di coperture del futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/\",\"name\":\"lifeherotile\",\"description\":\"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lifeherotile.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\",\"name\":\"Silvia Zambelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"caption\":\"Silvia Zambelli\"},\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/de\\\/author\\\/silvia-zambelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Life Herotile: sistemi di coperture del futuro - lifeherotile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/","og_locale":"de_DE","og_type":"article","og_title":"Life Herotile: sistemi di coperture del futuro - lifeherotile","og_description":"http:\/\/www.edilizianews.it\/articolo\/21640\/life-herotile-sistemi-di-coperture-del-futuro","og_url":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/","og_site_name":"lifeherotile","article_published_time":"2015-10-29T15:15:34+00:00","article_modified_time":"2016-05-02T11:02:33+00:00","og_image":[{"width":247,"height":118,"url":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg","type":"image\/jpeg"}],"author":"Silvia Zambelli","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Silvia Zambelli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#article","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/"},"author":{"name":"Silvia Zambelli","@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9"},"headline":"Life Herotile: sistemi di coperture del futuro","datePublished":"2015-10-29T15:15:34+00:00","dateModified":"2016-05-02T11:02:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/"},"wordCount":13,"image":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg","articleSection":["Press Release"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/","url":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/","name":"Life Herotile: sistemi di coperture del futuro - lifeherotile","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#primaryimage"},"image":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg","datePublished":"2015-10-29T15:15:34+00:00","dateModified":"2016-05-02T11:02:33+00:00","author":{"@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9"},"breadcrumb":{"@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#primaryimage","url":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg","contentUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2015\/10\/logo-edilizia.jpg","width":247,"height":118},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifeherotile.eu\/life-herotile-sistemi-di-coperture-del-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lifeherotile.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Life Herotile: sistemi di coperture del futuro"}]},{"@type":"WebSite","@id":"https:\/\/www.lifeherotile.eu\/#website","url":"https:\/\/www.lifeherotile.eu\/","name":"lifeherotile","description":"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifeherotile.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9","name":"Silvia Zambelli","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","caption":"Silvia Zambelli"},"url":"https:\/\/www.lifeherotile.eu\/de\/author\/silvia-zambelli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/1623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/comments?post=1623"}],"version-history":[{"count":1,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/1623\/revisions"}],"predecessor-version":[{"id":1625,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/1623\/revisions\/1625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/media\/1624"}],"wp:attachment":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/media?parent=1623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/categories?post=1623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/tags?post=1623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}