{"id":4158,"date":"2017-11-07T14:23:48","date_gmt":"2017-11-07T13:23:48","guid":{"rendered":"http:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/"},"modified":"2018-01-29T14:58:26","modified_gmt":"2018-01-29T13:58:26","slug":"the-municipality-halves-energy-costs-with-eco-tiles","status":"publish","type":"post","link":"https:\/\/www.lifeherotile.eu\/de\/the-municipality-halves-energy-costs-with-eco-tiles\/","title":{"rendered":"The municipality halves energy costs with eco-tiles"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_full  avia-builder-el-0  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><a href=\"http:\/\/gazzettadireggio.gelocal.it\/reggio\/cronaca\/2017\/11\/07\/news\/il-comune-dimezza-le-spese-energetiche-con-le-eco-tegole-1.16092835?refresh_ce\" target=\"_blank\">http:\/\/gazzettadireggio.gelocal.it\/reggio\/cronaca\/2017\/11\/07\/news\/il-comune-dimezza-le-spese-energetiche-con-le-eco-tegole-1.16092835?refresh_ce<\/a><\/p>\n<\/div><\/section><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-4158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-release-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The municipality halves energy costs with eco-tiles - lifeherotile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The municipality halves energy costs with eco-tiles - lifeherotile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/\" \/>\n<meta property=\"og:site_name\" content=\"lifeherotile\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-07T13:23:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-29T13:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"611\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Silvia Zambelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Zambelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/\"},\"author\":{\"name\":\"Silvia Zambelli\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\"},\"headline\":\"The municipality halves energy costs with eco-tiles\",\"datePublished\":\"2017-11-07T13:23:48+00:00\",\"dateModified\":\"2018-01-29T13:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/\"},\"wordCount\":72,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Monitoraggio-parte-tetto-611x457.jpg\",\"articleSection\":[\"Press Release\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/\",\"name\":\"The municipality halves energy costs with eco-tiles - lifeherotile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Monitoraggio-parte-tetto-611x457.jpg\",\"datePublished\":\"2017-11-07T13:23:48+00:00\",\"dateModified\":\"2018-01-29T13:58:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Monitoraggio-parte-tetto-611x457.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lifeherotile.eu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Monitoraggio-parte-tetto-611x457.jpg\",\"width\":611,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/the-municipality-halves-energy-costs-with-eco-tiles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lifeherotile.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The municipality halves energy costs with eco-tiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/\",\"name\":\"lifeherotile\",\"description\":\"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lifeherotile.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#\\\/schema\\\/person\\\/a37a30d8138a4585bf9ed983fec9e2e9\",\"name\":\"Silvia Zambelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g\",\"caption\":\"Silvia Zambelli\"},\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/de\\\/author\\\/silvia-zambelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The municipality halves energy costs with eco-tiles - lifeherotile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/","og_locale":"de_DE","og_type":"article","og_title":"The municipality halves energy costs with eco-tiles - lifeherotile","og_url":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/","og_site_name":"lifeherotile","article_published_time":"2017-11-07T13:23:48+00:00","article_modified_time":"2018-01-29T13:58:26+00:00","og_image":[{"width":611,"height":457,"url":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg","type":"image\/jpeg"}],"author":"Silvia Zambelli","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Silvia Zambelli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#article","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/"},"author":{"name":"Silvia Zambelli","@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9"},"headline":"The municipality halves energy costs with eco-tiles","datePublished":"2017-11-07T13:23:48+00:00","dateModified":"2018-01-29T13:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/"},"wordCount":72,"commentCount":0,"image":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg","articleSection":["Press Release"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/","url":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/","name":"The municipality halves energy costs with eco-tiles - lifeherotile","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#primaryimage"},"image":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg","datePublished":"2017-11-07T13:23:48+00:00","dateModified":"2018-01-29T13:58:26+00:00","author":{"@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9"},"breadcrumb":{"@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#primaryimage","url":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg","contentUrl":"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2017\/11\/Monitoraggio-parte-tetto-611x457.jpg","width":611,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifeherotile.eu\/the-municipality-halves-energy-costs-with-eco-tiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lifeherotile.eu\/de\/"},{"@type":"ListItem","position":2,"name":"The municipality halves energy costs with eco-tiles"}]},{"@type":"WebSite","@id":"https:\/\/www.lifeherotile.eu\/#website","url":"https:\/\/www.lifeherotile.eu\/","name":"lifeherotile","description":"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifeherotile.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.lifeherotile.eu\/#\/schema\/person\/a37a30d8138a4585bf9ed983fec9e2e9","name":"Silvia Zambelli","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3b38a468a3c2017dcff43e2502adcc88c533bc0119d8a16610292870251c1d3?s=96&d=mm&r=g","caption":"Silvia Zambelli"},"url":"https:\/\/www.lifeherotile.eu\/de\/author\/silvia-zambelli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/4158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/comments?post=4158"}],"version-history":[{"count":1,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/4158\/revisions"}],"predecessor-version":[{"id":4160,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/posts\/4158\/revisions\/4160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/media\/3876"}],"wp:attachment":[{"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/media?parent=4158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/categories?post=4158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/de\/wp-json\/wp\/v2\/tags?post=4158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}