{"id":3807,"date":"2017-09-14T11:44:29","date_gmt":"2017-09-14T09:44:29","guid":{"rendered":"http:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/"},"modified":"2017-09-14T12:12:58","modified_gmt":"2017-09-14T10:12:58","slug":"installation-of-tiles-cadelbosco","status":"publish","type":"page","link":"https:\/\/www.lifeherotile.eu\/it\/installation-of-tiles-cadelbosco\/","title":{"rendered":"Installation of Tiles Cadelbosco"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_full  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Installazione della nuova tegola marsigliese e delle sonde di acquisizione a Cadelbosco (RE) per l\u2019avvio dei monitoraggi sull\u2019edificio reale.<\/h3>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-5ea7596238ed9f191e6b5e662093052f\">\n#top .hr.hr-invisible.av-av_hr-5ea7596238ed9f191e6b5e662093052f{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-av_hr-5ea7596238ed9f191e6b5e662093052f hr-invisible  avia-builder-el-2  el_after_av_textblock  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_half  avia-builder-el-3  el_after_av_one_full  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-2a64de42b738552fe666ca889af77e28\">\n.flex_column.av-av_one_half-2a64de42b738552fe666ca889af77e28{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-2a64de42b738552fe666ca889af77e28 av_one_half  avia-builder-el-5  el_after_av_one_half  el_before_av_one_half  flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb\">\n.flex_column.av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-352b07ef7d3bc99b2e9f92e7a9e06bdb av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-2a64de42b738552fe666ca889af77e28\">\n.flex_column.av-av_one_half-2a64de42b738552fe666ca889af77e28{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-2a64de42b738552fe666ca889af77e28 av_one_half  avia-builder-el-9  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3807","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Installation of Tiles Cadelbosco - lifeherotile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installation of Tiles Cadelbosco - lifeherotile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/\" \/>\n<meta property=\"og:site_name\" content=\"lifeherotile\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-14T10:12:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/installation-of-tiles-cadelbosco\\\/\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/installation-of-tiles-cadelbosco\\\/\",\"name\":\"Installation of Tiles Cadelbosco - lifeherotile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\"},\"datePublished\":\"2017-09-14T09:44:29+00:00\",\"dateModified\":\"2017-09-14T10:12:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/installation-of-tiles-cadelbosco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lifeherotile.eu\\\/installation-of-tiles-cadelbosco\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/installation-of-tiles-cadelbosco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installation of Tiles Cadelbosco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/\",\"name\":\"lifeherotile\",\"description\":\"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lifeherotile.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installation of Tiles Cadelbosco - lifeherotile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/","og_locale":"it_IT","og_type":"article","og_title":"Installation of Tiles Cadelbosco - lifeherotile","og_url":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/","og_site_name":"lifeherotile","article_modified_time":"2017-09-14T10:12:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/","url":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/","name":"Installation of Tiles Cadelbosco - lifeherotile","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/#website"},"datePublished":"2017-09-14T09:44:29+00:00","dateModified":"2017-09-14T10:12:58+00:00","breadcrumb":{"@id":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifeherotile.eu\/installation-of-tiles-cadelbosco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lifeherotile.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Installation of Tiles Cadelbosco"}]},{"@type":"WebSite","@id":"https:\/\/www.lifeherotile.eu\/#website","url":"https:\/\/www.lifeherotile.eu\/","name":"lifeherotile","description":"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifeherotile.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/3807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/comments?post=3807"}],"version-history":[{"count":2,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/3807\/revisions"}],"predecessor-version":[{"id":3809,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/3807\/revisions\/3809"}],"wp:attachment":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/media?parent=3807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}