{"id":4392,"date":"2018-08-06T12:58:58","date_gmt":"2018-08-06T10:58:58","guid":{"rendered":"http:\/\/www.lifeherotile.eu\/?page_id=4392"},"modified":"2018-08-06T12:58:58","modified_gmt":"2018-08-06T10:58:58","slug":"life-herotile-al-mock-yeruham","status":"publish","type":"page","link":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/","title":{"rendered":"Life HEROTile al mock up di Yeruham"},"content":{"rendered":"<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Life HEROTile al mock up di Yeruham<\/strong><\/p>\n<p><strong>19 &#8211; 23 Aprile, Yeruham, Israel<\/strong><\/p>\n<p>In Aprile, con la supervisione del partner scientifico del progetto LIFE-Herotile, Universit\u00e0 degli Studi di Ferrara, si sta procedendo all&#8217;installazione delle tegole innovative in laterizio su mock up appositamente realizzato presso la sede dell\u2019industria CAI, produttrice di tegole in laterizio, a Yeruham in Israele, ai bordi del deserto del Negev dove sussistono condizioni climatiche di un certo rilievo.<br \/>\nIl mock up \u00e8 caratterizzato da una serie di falde: alcune realizzate con le nuove tegole Herotile marsigliese e portoghese, altre da tegole marsigliesi e portoghesi standard di produzione corrente e da una copertura in lastre di metallo stampato di colore simile a quello del laterizio.<br \/>\nLo scopo \u00e8 consentire un confronto fra le prestazioni delle diverse tipologie di manto in analoghe condizioni di esposizione.<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_gallery-be07bc4c3e8b35b35695f6793ca405ed\">\n#top .avia-gallery.av-av_gallery-be07bc4c3e8b35b35695f6793ca405ed .avia-gallery-thumb a{\nwidth:20%;\n}\n<\/style>\n<div  class='avia-gallery av-av_gallery-be07bc4c3e8b35b35695f6793ca405ed avia_animate_when_visible  avia-builder-el-1  el_after_av_textblock  avia-builder-el-last  avia_lazyload avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31183585_787039081490537_1397276939432047707_n.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31183585_787039081490537_1397276939432047707_n-495x400.jpg' class='first_thumb lightbox ' data-onclick='1' title='31183585_787039081490537_1397276939432047707_n'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4405 avia-img-lazy-loading-not-4405\"   src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31183585_787039081490537_1397276939432047707_n-495x400.jpg' width='495' height='400'  title='31183585_787039081490537_1397276939432047707_n' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4405 avia-img-lazy-loading-4405\"  width='495' height='400' src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31183585_787039081490537_1397276939432047707_n-495x400.jpg' title='31183585_787039081490537_1397276939432047707_n' alt='' \/><\/div><\/a><a href=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31172206_787038984823880_4539878255143606638_n.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31172206_787038984823880_4539878255143606638_n-495x400.jpg' class='lightbox ' data-onclick='2' title='31172206_787038984823880_4539878255143606638_n'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4401 avia-img-lazy-loading-not-4401\"   src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31172206_787038984823880_4539878255143606638_n-495x400.jpg' width='495' height='400'  title='31172206_787038984823880_4539878255143606638_n' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4401 avia-img-lazy-loading-4401\"  width='495' height='400' src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31172206_787038984823880_4539878255143606638_n-495x400.jpg' title='31172206_787038984823880_4539878255143606638_n' alt='' \/><\/div><\/a><a href=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31241931_787038974823881_2341073490793696314_n.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31241931_787038974823881_2341073490793696314_n-495x400.jpg' class='lightbox ' data-onclick='3' title='31241931_787038974823881_2341073490793696314_n'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4409 avia-img-lazy-loading-not-4409\"   src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31241931_787038974823881_2341073490793696314_n-495x400.jpg' width='495' height='400'  title='31241931_787038974823881_2341073490793696314_n' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4409 avia-img-lazy-loading-4409\"  width='495' height='400' src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31241931_787038974823881_2341073490793696314_n-495x400.jpg' title='31241931_787038974823881_2341073490793696314_n' alt='' \/><\/div><\/a><a href=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31252877_787039028157209_2848372439248856836_n.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31252877_787039028157209_2848372439248856836_n-495x400.jpg' class='lightbox ' data-onclick='4' title='31252877_787039028157209_2848372439248856836_n'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4413 avia-img-lazy-loading-not-4413\"   src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31252877_787039028157209_2848372439248856836_n-495x400.jpg' width='495' height='400'  title='31252877_787039028157209_2848372439248856836_n' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4413 avia-img-lazy-loading-4413\"  width='495' height='400' src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31252877_787039028157209_2848372439248856836_n-495x400.jpg' title='31252877_787039028157209_2848372439248856836_n' alt='' \/><\/div><\/a><a href=\"https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31164166_787039031490542_3890540715590094600_n.jpg\" data-rel='gallery-1' data-prev-img='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31164166_787039031490542_3890540715590094600_n-495x400.jpg' class='lightbox ' data-onclick='5' title='31164166_787039031490542_3890540715590094600_n'  itemprop=\"thumbnailUrl\"  ><img fetchpriority=\"high\" class=\"wp-image-4397 avia-img-lazy-loading-not-4397\"   src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31164166_787039031490542_3890540715590094600_n-495x400.jpg' width='495' height='400'  title='31164166_787039031490542_3890540715590094600_n' alt='' \/><div class='big-prev-fake'><img loading=\"lazy\" class=\"wp-image-4397 avia-img-lazy-loading-4397\"  width='495' height='400' src='https:\/\/www.lifeherotile.eu\/wp-content\/uploads\/2018\/08\/31164166_787039031490542_3890540715590094600_n-495x400.jpg' title='31164166_787039031490542_3890540715590094600_n' alt='' \/><\/div><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4392","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Life HEROTile al mock up di Yeruham - lifeherotile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Life HEROTile al mock up di Yeruham - lifeherotile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/\" \/>\n<meta property=\"og:site_name\" content=\"lifeherotile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/life-herotile-al-mock-yeruham\\\/\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/life-herotile-al-mock-yeruham\\\/\",\"name\":\"Life HEROTile al mock up di Yeruham - lifeherotile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\"},\"datePublished\":\"2018-08-06T10:58:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/life-herotile-al-mock-yeruham\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/life-herotile-al-mock-yeruham\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/life-herotile-al-mock-yeruham\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lifeherotile.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life HEROTile al mock up di Yeruham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lifeherotile.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.lifeherotile.eu\\\/\",\"name\":\"lifeherotile\",\"description\":\"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lifeherotile.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Life HEROTile al mock up di Yeruham - lifeherotile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/","og_locale":"it_IT","og_type":"article","og_title":"Life HEROTile al mock up di Yeruham - lifeherotile","og_url":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/","og_site_name":"lifeherotile","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/","url":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/","name":"Life HEROTile al mock up di Yeruham - lifeherotile","isPartOf":{"@id":"https:\/\/www.lifeherotile.eu\/#website"},"datePublished":"2018-08-06T10:58:58+00:00","breadcrumb":{"@id":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifeherotile.eu\/it\/life-herotile-al-mock-yeruham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lifeherotile.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Life HEROTile al mock up di Yeruham"}]},{"@type":"WebSite","@id":"https:\/\/www.lifeherotile.eu\/#website","url":"https:\/\/www.lifeherotile.eu\/","name":"lifeherotile","description":"High Energy savings in building cooling by ROof TILEs shape optimization toward a better above sheathing ventilation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifeherotile.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/4392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/comments?post=4392"}],"version-history":[{"count":2,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/4392\/revisions"}],"predecessor-version":[{"id":4418,"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/pages\/4392\/revisions\/4418"}],"wp:attachment":[{"href":"https:\/\/www.lifeherotile.eu\/it\/wp-json\/wp\/v2\/media?parent=4392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}